{"id":7802,"count":1,"description":"","link":"https:\/\/universidadedacapoeira.com\/index.php\/tag\/avatar-giovanni-dioimedson-de-andrade\/","name":"Avatar - Giovanni Dioimedson de Andrade","slug":"avatar-giovanni-dioimedson-de-andrade","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/tags\/7802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts?tags=7802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}