{"id":9210,"date":"2024-09-12T07:11:22","date_gmt":"2024-09-12T10:11:22","guid":{"rendered":"http:\/\/universidadedacapoeira.com\/?p=9210"},"modified":"2024-09-12T07:11:22","modified_gmt":"2024-09-12T10:11:22","slug":"berimbau-solo-mestrs-polemico-laura-e-mandingueiro-tiguera-360-juiz-de-fora-img_5678-214-gb-15h00-06ago24","status":"publish","type":"post","link":"https:\/\/universidadedacapoeira.com\/index.php\/2024\/09\/12\/berimbau-solo-mestrs-polemico-laura-e-mandingueiro-tiguera-360-juiz-de-fora-img_5678-214-gb-15h00-06ago24\/","title":{"rendered":"Berimbau Solo. Mestr@s Pol\u00eamico, Laura e Mandingueiro. Tig\u00fc\u00e9ra 360, Juiz de Fora. IMG_5678. 2,14 GB. 15h00. 06Ago24."},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"UNICAPOEIRA MEIA LUA - Berimbau - Mestr@s Pol\u00eamico, Mandingueiro e Laura. IMG_5678. 2,14 GB. 06Ago24\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5WgXkjIX94w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Berimbau Solo. Mestr@s Pol\u00eamico, Laura Cavalieri Bisio e Mandingueiro &#8211; Peter Faluhelyi. Sala de Entrar, Tig\u00fc\u00e9ra 360, Juiz de Fora, Minas Gerais\/MG, Brasil. Registro de Capoeira Mestre Pol\u00eamico &#8211; Professor Doutor Jo\u00e3o Couto Teixeira. IMG_5678. 2,14 GB. 15h00. Ter\u00e7a-feira, 06 de Agosto de 2024. HD 1080p. MOV.<br \/>\nUniversidade Livre de Estudos Culturais da Capoeira &#8211; Universidade da Capoeira &#8211; UNICAPOEIRA, Instituto de Educa\u00e7\u00e3o Socioambiental &#8211; IESAMBI, Associa\u00e7\u00e3o de Capoeira &#8211; ASCA e Grupo de Capoeira MEIA LUA &#8211; Fundado Ter\u00e7a-feira, 29 de Maio de 1962. Orquestra Harm\u00f4nica de Berimbaus.<\/p>\n<p>Seja membro deste canal e ganhe benef\u00edcios:<br \/>\nhttps:\/\/www.youtube.com\/channel\/UCE6HrA5Y_VZ4-hgw8FG13aw\/join<br \/>\nPIX &#8211; polemico72@hotmail.com<\/p>\n","protected":false},"author":2,"featured_media":9211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[4676],"tags":[2605,8376,6114,8377,236,247,8171,7948,7699,6483,411],"class_list":["post-9210","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-orquestra-harmonica-de-berimbaus","tag-associacao-de-capoeira-asca","tag-berimbau-solo-mestrs-laura-cavalieri-bisio-e-mandingueiro-peter-faluhelyi","tag-grupo-de-capoeira-meia-lua-fundado-terca-feira-29-de-maio-de-1962","tag-img_5678-2-14-gb-15h00-terca-feira-06-de-agosto-de-2024","tag-instituto-de-educacao-socioambiental-iesambi","tag-orquestra-harmonica-de-berimbaus","tag-pix-polemico72hotmail-com","tag-registro-de-capoeira-mestre-polemico-professor-doutor-joao-couto-teixeira","tag-sala-de-entrar-tiguera-360-juiz-de-fora-minas-gerais-mg-brasil","tag-seja-membro-deste-canal-e-ganhe-beneficios-https-www-youtube-com-channel-uce6hra5y_vz4-hgw8fg13aw-join","tag-universidade-livre-de-estudos-culturais-da-capoeira-universidade-da-capoeira-unicapoeira","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts\/9210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/comments?post=9210"}],"version-history":[{"count":1,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts\/9210\/revisions"}],"predecessor-version":[{"id":9212,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts\/9210\/revisions\/9212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/media\/9211"}],"wp:attachment":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/media?parent=9210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/categories?post=9210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/tags?post=9210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}