{"id":8062,"date":"2023-12-11T14:48:05","date_gmt":"2023-12-11T17:48:05","guid":{"rendered":"http:\/\/universidadedacapoeira.com\/?p=8062"},"modified":"2023-12-11T14:48:05","modified_gmt":"2023-12-11T17:48:05","slug":"novena-a-padroeira-celebracao-da-palavra-e-adoracao-ao-santissimo-diacono-marcio-ministrs-rogerio-e-maria-angelica-acolhida-isabel-igreja-nossa-senhora-mae-de-deus-juiz-de-fora-img_8974-5-10","status":"publish","type":"post","link":"https:\/\/universidadedacapoeira.com\/index.php\/2023\/12\/11\/novena-a-padroeira-celebracao-da-palavra-e-adoracao-ao-santissimo-diacono-marcio-ministrs-rogerio-e-maria-angelica-acolhida-isabel-igreja-nossa-senhora-mae-de-deus-juiz-de-fora-img_8974-5-10\/","title":{"rendered":"Novena \u00e0 Padroeira. Celebra\u00e7\u00e3o da Palavra e Adora\u00e7\u00e3o ao Sant\u00edssimo. Di\u00e1cono M\u00e1rcio. Ministr@s Rog\u00e9rio e Maria Ang\u00e9lica. Acolhida Isabel. Igreja Nossa Senhora M\u00e3e de Deus, Juiz de Fora. IMG_8974\/5. 10,15 GB. 19h30. 06Set23."},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Novena: Di\u00e1cono M\u00e1rcio. Igreja Nossa Senhora M\u00e3e de Deus, Juiz de Fora. IMG_8974. 10 GB. 06Set23. 8\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/jydJV2h_8Y8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Novena \u00e0 Padroeira. Celebra\u00e7\u00e3o da Palavra e Adora\u00e7\u00e3o ao Sant\u00edssimo. Di\u00e1cono M\u00e1rcio Rosa dos Santos. Ministr@s Extraordin\u00e1rios da Sagrada Comunh\u00e3o Rog\u00e9rio e Maria Ang\u00e9lica A. de Moraes Tavares. Acolhida Isabel. Igreja Nossa Senhora M\u00e3e de Deus, Bairro Nossa Senhora de Lourdes, Juiz de Fora, Minas Gerais\/MG, Brasil. Registro de Capoeira Mestre Pol\u00eamico &#8211; Professor Jo\u00e3o Couto Teixeira. IMG_8974\/5. 10,15 GB. 19h30. Quarta-feira, 06 de Setembro de 2023. HD 1080p. 8.<br \/>\nUniversidade Livre de Estudos Culturais da Capoeira &#8211; Universidade da Capoeira &#8211; UNICAPOEIRA, Instituto de Educa\u00e7\u00e3o Socioambiental &#8211; IESAMBI, Associa\u00e7\u00e3o de Capoeira &#8211; ASCA e Grupo de Capoeira MEIA LUA &#8211; Fundado Ter\u00e7a-feira, 29 de Maio de 1962.<\/p>\n<p>Seja membro deste canal e ganhe benef\u00edcios:<br \/>\nhttps:\/\/www.youtube.com\/channel\/UCE6HrA5Y_VZ4-hgw8FG13aw\/join<\/p>\n","protected":false},"author":2,"featured_media":8063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[4674],"tags":[1700,544,1494,7015,2605,942,43,7013,4234,6114,1742,4196,7016,236,55,237,7014,6949,7017,519,6483,411],"class_list":["post-8062","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-celebracao-eucaristica","tag-10-15-gb","tag-19h30","tag-1494","tag-acolhida-isabel","tag-associacao-de-capoeira-asca","tag-bairro-nossa-senhora-de-lourdes","tag-brasil","tag-celebracao-da-palavra-e-adoracao-ao-santissimo","tag-diacono-marcio-rosa-dos-santos","tag-grupo-de-capoeira-meia-lua-fundado-terca-feira-29-de-maio-de-1962","tag-hd-1080p","tag-igreja-nossa-senhora-mae-de-deus","tag-img_8974-5","tag-instituto-de-educacao-socioambiental-iesambi","tag-juiz-de-fora","tag-minas-gerais-mg-3","tag-ministros-extraordinarios-da-sagrada-comunhao-rogerio-e-maria-angelica-a-de-moraes-tavares","tag-novena-a-padroeira","tag-quarta-feira-06-de-setembro-de-2023","tag-registro-de-capoeira-mestre-polemico-professor-joao-couto-teixeira","tag-seja-membro-deste-canal-e-ganhe-beneficios-https-www-youtube-com-channel-uce6hra5y_vz4-hgw8fg13aw-join","tag-universidade-livre-de-estudos-culturais-da-capoeira-universidade-da-capoeira-unicapoeira","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts\/8062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/comments?post=8062"}],"version-history":[{"count":1,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts\/8062\/revisions"}],"predecessor-version":[{"id":8064,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/posts\/8062\/revisions\/8064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/media\/8063"}],"wp:attachment":[{"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/media?parent=8062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/categories?post=8062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/universidadedacapoeira.com\/index.php\/wp-json\/wp\/v2\/tags?post=8062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}